{"id":1902,"count":1,"description":"","link":"http:\/\/blueroanmedia.digital\/index.php\/category\/drinkchicagostyle-com\/","name":"drinkchicagostyle.com","slug":"drinkchicagostyle-com","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/blueroanmedia.digital\/index.php\/wp-json\/wp\/v2\/categories\/1902"}],"collection":[{"href":"http:\/\/blueroanmedia.digital\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/blueroanmedia.digital\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/blueroanmedia.digital\/index.php\/wp-json\/wp\/v2\/posts?categories=1902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}